{"id":6018,"date":"2026-07-15T11:57:40","date_gmt":"2026-07-15T09:57:40","guid":{"rendered":"https:\/\/www.deutsche-yachten.de\/?post_type=news-beitrag&#038;p=6018"},"modified":"2026-07-15T11:57:41","modified_gmt":"2026-07-15T09:57:41","slug":"deutsche-yachten-welcomes-two-new-members-2","status":"publish","type":"news-beitrag","link":"https:\/\/www.deutsche-yachten.de\/en\/news-beitrag\/deutsche-yachten-welcomes-two-new-members-2\/","title":{"rendered":"Deutsche Yachten welcomes two new members"},"content":{"rendered":"","protected":false},"featured_media":6015,"template":"","meta":{"_acf_changed":true},"news-mitglied":[79],"class_list":["post-6018","news-beitrag","type-news-beitrag","status-publish","has-post-thumbnail","hentry","news-mitglied-uhsadel-rechtsanwalte-partgmbb"],"acf":[],"aioseo_notices":[],"aioseo_head":"\n\t\t<!-- All in One SEO Pro 4.9.10 - aioseo.com -->\n\t<meta name=\"robots\" content=\"max-image-preview:large\" \/>\n\t<link rel=\"canonical\" href=\"https:\/\/www.deutsche-yachten.de\/en\/news-beitrag\/deutsche-yachten-welcomes-two-new-members-2\/\" \/>\n\t<meta name=\"generator\" content=\"All in One SEO Pro (AIOSEO) 4.9.10\" \/>\n\t\t<meta property=\"og:locale\" content=\"en_US\" \/>\n\t\t<meta property=\"og:site_name\" content=\"Deutsche Yachten -\" \/>\n\t\t<meta property=\"og:type\" content=\"article\" \/>\n\t\t<meta property=\"og:title\" content=\"Deutsche Yachten welcomes two new members - Deutsche Yachten\" \/>\n\t\t<meta property=\"og:url\" content=\"https:\/\/www.deutsche-yachten.de\/en\/news-beitrag\/deutsche-yachten-welcomes-two-new-members-2\/\" \/>\n\t\t<meta property=\"og:image\" content=\"https:\/\/www.deutsche-yachten.de\/wp-content\/uploads\/2026\/07\/Neues-Mitglied-Uhsadel-JFM.jpg\" \/>\n\t\t<meta property=\"og:image:secure_url\" content=\"https:\/\/www.deutsche-yachten.de\/wp-content\/uploads\/2026\/07\/Neues-Mitglied-Uhsadel-JFM.jpg\" \/>\n\t\t<meta property=\"og:image:width\" content=\"1200\" \/>\n\t\t<meta property=\"og:image:height\" content=\"630\" \/>\n\t\t<meta property=\"article:published_time\" content=\"2026-07-15T09:57:40+00:00\" \/>\n\t\t<meta property=\"article:modified_time\" content=\"2026-07-15T09:57:41+00:00\" \/>\n\t\t<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n\t\t<meta name=\"twitter:title\" content=\"Deutsche Yachten welcomes two new members - Deutsche Yachten\" \/>\n\t\t<meta name=\"twitter:image\" content=\"https:\/\/www.deutsche-yachten.de\/wp-content\/uploads\/2026\/07\/Neues-Mitglied-Uhsadel-JFM.jpg\" \/>\n\t\t<script type=\"application\/ld+json\" class=\"aioseo-schema\">\n\t\t\t{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.deutsche-yachten.de\\\/en\\\/news-beitrag\\\/deutsche-yachten-welcomes-two-new-members-2\\\/#breadcrumblist\",\"itemListElement\":[{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.deutsche-yachten.de\\\/en\\\/#listItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.deutsche-yachten.de\\\/en\\\/\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.deutsche-yachten.de\\\/en\\\/news-mitglied\\\/uhsadel-rechtsanwalte-partgmbb\\\/#listItem\",\"name\":\"Uhsadel Rechtsanw\\u00e4lte PartGmbB\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.deutsche-yachten.de\\\/en\\\/news-mitglied\\\/uhsadel-rechtsanwalte-partgmbb\\\/#listItem\",\"position\":2,\"name\":\"Uhsadel Rechtsanw\\u00e4lte PartGmbB\",\"item\":\"https:\\\/\\\/www.deutsche-yachten.de\\\/en\\\/news-mitglied\\\/uhsadel-rechtsanwalte-partgmbb\\\/\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.deutsche-yachten.de\\\/en\\\/news-beitrag\\\/deutsche-yachten-welcomes-two-new-members-2\\\/#listItem\",\"name\":\"Deutsche Yachten welcomes two new members\"},\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.deutsche-yachten.de\\\/en\\\/#listItem\",\"name\":\"Home\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.deutsche-yachten.de\\\/en\\\/news-beitrag\\\/deutsche-yachten-welcomes-two-new-members-2\\\/#listItem\",\"position\":3,\"name\":\"Deutsche Yachten welcomes two new members\",\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.deutsche-yachten.de\\\/en\\\/news-mitglied\\\/uhsadel-rechtsanwalte-partgmbb\\\/#listItem\",\"name\":\"Uhsadel Rechtsanw\\u00e4lte PartGmbB\"}}]},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.deutsche-yachten.de\\\/en\\\/#organization\",\"name\":\"Deutsche Yachten\",\"url\":\"https:\\\/\\\/www.deutsche-yachten.de\\\/en\\\/\",\"telephone\":\"+494030706790\",\"logo\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/www.deutsche-yachten.de\\\/wp-content\\\/uploads\\\/2025\\\/04\\\/deutsche-yachten-logo-blau.svg\",\"@id\":\"https:\\\/\\\/www.deutsche-yachten.de\\\/en\\\/news-beitrag\\\/deutsche-yachten-welcomes-two-new-members-2\\\/#organizationLogo\"},\"image\":{\"@id\":\"https:\\\/\\\/www.deutsche-yachten.de\\\/en\\\/news-beitrag\\\/deutsche-yachten-welcomes-two-new-members-2\\\/#organizationLogo\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.deutsche-yachten.de\\\/en\\\/news-beitrag\\\/deutsche-yachten-welcomes-two-new-members-2\\\/#webpage\",\"url\":\"https:\\\/\\\/www.deutsche-yachten.de\\\/en\\\/news-beitrag\\\/deutsche-yachten-welcomes-two-new-members-2\\\/\",\"name\":\"Deutsche Yachten welcomes two new members - Deutsche Yachten\",\"inLanguage\":\"en-US\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.deutsche-yachten.de\\\/en\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.deutsche-yachten.de\\\/en\\\/news-beitrag\\\/deutsche-yachten-welcomes-two-new-members-2\\\/#breadcrumblist\"},\"image\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/www.deutsche-yachten.de\\\/wp-content\\\/uploads\\\/2026\\\/07\\\/Neues-Mitglied-Uhsadel-JFM.jpg\",\"@id\":\"https:\\\/\\\/www.deutsche-yachten.de\\\/en\\\/news-beitrag\\\/deutsche-yachten-welcomes-two-new-members-2\\\/#mainImage\",\"width\":1200,\"height\":630},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.deutsche-yachten.de\\\/en\\\/news-beitrag\\\/deutsche-yachten-welcomes-two-new-members-2\\\/#mainImage\"},\"datePublished\":\"2026-07-15T11:57:40+02:00\",\"dateModified\":\"2026-07-15T11:57:41+02:00\"},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.deutsche-yachten.de\\\/en\\\/#website\",\"url\":\"https:\\\/\\\/www.deutsche-yachten.de\\\/en\\\/\",\"name\":\"Deutsche Yachten\",\"inLanguage\":\"en-US\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.deutsche-yachten.de\\\/en\\\/#organization\"}}]}\n\t\t<\/script>\n\t\t<!-- All in One SEO Pro -->\r\n\t\t<title>Deutsche Yachten welcomes two new members - Deutsche Yachten<\/title>\n\n","aioseo_head_json":{"title":"Deutsche Yachten welcomes two new members - Deutsche Yachten","description":"","canonical_url":"https:\/\/www.deutsche-yachten.de\/en\/news-beitrag\/deutsche-yachten-welcomes-two-new-members-2\/","robots":"max-image-preview:large","keywords":"","webmasterTools":{"miscellaneous":""},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"BreadcrumbList","@id":"https:\/\/www.deutsche-yachten.de\/en\/news-beitrag\/deutsche-yachten-welcomes-two-new-members-2\/#breadcrumblist","itemListElement":[{"@type":"ListItem","@id":"https:\/\/www.deutsche-yachten.de\/en\/#listItem","position":1,"name":"Home","item":"https:\/\/www.deutsche-yachten.de\/en\/","nextItem":{"@type":"ListItem","@id":"https:\/\/www.deutsche-yachten.de\/en\/news-mitglied\/uhsadel-rechtsanwalte-partgmbb\/#listItem","name":"Uhsadel Rechtsanw\u00e4lte PartGmbB"}},{"@type":"ListItem","@id":"https:\/\/www.deutsche-yachten.de\/en\/news-mitglied\/uhsadel-rechtsanwalte-partgmbb\/#listItem","position":2,"name":"Uhsadel Rechtsanw\u00e4lte PartGmbB","item":"https:\/\/www.deutsche-yachten.de\/en\/news-mitglied\/uhsadel-rechtsanwalte-partgmbb\/","nextItem":{"@type":"ListItem","@id":"https:\/\/www.deutsche-yachten.de\/en\/news-beitrag\/deutsche-yachten-welcomes-two-new-members-2\/#listItem","name":"Deutsche Yachten welcomes two new members"},"previousItem":{"@type":"ListItem","@id":"https:\/\/www.deutsche-yachten.de\/en\/#listItem","name":"Home"}},{"@type":"ListItem","@id":"https:\/\/www.deutsche-yachten.de\/en\/news-beitrag\/deutsche-yachten-welcomes-two-new-members-2\/#listItem","position":3,"name":"Deutsche Yachten welcomes two new members","previousItem":{"@type":"ListItem","@id":"https:\/\/www.deutsche-yachten.de\/en\/news-mitglied\/uhsadel-rechtsanwalte-partgmbb\/#listItem","name":"Uhsadel Rechtsanw\u00e4lte PartGmbB"}}]},{"@type":"Organization","@id":"https:\/\/www.deutsche-yachten.de\/en\/#organization","name":"Deutsche Yachten","url":"https:\/\/www.deutsche-yachten.de\/en\/","telephone":"+494030706790","logo":{"@type":"ImageObject","url":"https:\/\/www.deutsche-yachten.de\/wp-content\/uploads\/2025\/04\/deutsche-yachten-logo-blau.svg","@id":"https:\/\/www.deutsche-yachten.de\/en\/news-beitrag\/deutsche-yachten-welcomes-two-new-members-2\/#organizationLogo"},"image":{"@id":"https:\/\/www.deutsche-yachten.de\/en\/news-beitrag\/deutsche-yachten-welcomes-two-new-members-2\/#organizationLogo"}},{"@type":"WebPage","@id":"https:\/\/www.deutsche-yachten.de\/en\/news-beitrag\/deutsche-yachten-welcomes-two-new-members-2\/#webpage","url":"https:\/\/www.deutsche-yachten.de\/en\/news-beitrag\/deutsche-yachten-welcomes-two-new-members-2\/","name":"Deutsche Yachten welcomes two new members - Deutsche Yachten","inLanguage":"en-US","isPartOf":{"@id":"https:\/\/www.deutsche-yachten.de\/en\/#website"},"breadcrumb":{"@id":"https:\/\/www.deutsche-yachten.de\/en\/news-beitrag\/deutsche-yachten-welcomes-two-new-members-2\/#breadcrumblist"},"image":{"@type":"ImageObject","url":"https:\/\/www.deutsche-yachten.de\/wp-content\/uploads\/2026\/07\/Neues-Mitglied-Uhsadel-JFM.jpg","@id":"https:\/\/www.deutsche-yachten.de\/en\/news-beitrag\/deutsche-yachten-welcomes-two-new-members-2\/#mainImage","width":1200,"height":630},"primaryImageOfPage":{"@id":"https:\/\/www.deutsche-yachten.de\/en\/news-beitrag\/deutsche-yachten-welcomes-two-new-members-2\/#mainImage"},"datePublished":"2026-07-15T11:57:40+02:00","dateModified":"2026-07-15T11:57:41+02:00"},{"@type":"WebSite","@id":"https:\/\/www.deutsche-yachten.de\/en\/#website","url":"https:\/\/www.deutsche-yachten.de\/en\/","name":"Deutsche Yachten","inLanguage":"en-US","publisher":{"@id":"https:\/\/www.deutsche-yachten.de\/en\/#organization"}}]},"og:locale":"en_US","og:site_name":"Deutsche Yachten -","og:type":"article","og:title":"Deutsche Yachten welcomes two new members - Deutsche Yachten","og:url":"https:\/\/www.deutsche-yachten.de\/en\/news-beitrag\/deutsche-yachten-welcomes-two-new-members-2\/","og:image":"https:\/\/www.deutsche-yachten.de\/wp-content\/uploads\/2026\/07\/Neues-Mitglied-Uhsadel-JFM.jpg","og:image:secure_url":"https:\/\/www.deutsche-yachten.de\/wp-content\/uploads\/2026\/07\/Neues-Mitglied-Uhsadel-JFM.jpg","og:image:width":1200,"og:image:height":630,"article:published_time":"2026-07-15T09:57:40+00:00","article:modified_time":"2026-07-15T09:57:41+00:00","twitter:card":"summary_large_image","twitter:title":"Deutsche Yachten welcomes two new members - Deutsche Yachten","twitter:image":"https:\/\/www.deutsche-yachten.de\/wp-content\/uploads\/2026\/07\/Neues-Mitglied-Uhsadel-JFM.jpg"},"aioseo_meta_data":{"post_id":"6018","title":null,"description":null,"keywords":null,"keyphrases":{"focus":{"keyphrase":"","score":0,"analysis":{"keyphraseInTitle":{"score":0,"maxScore":9,"error":1}}},"additional":[]},"primary_term":null,"canonical_url":null,"og_title":null,"og_description":null,"og_object_type":"default","og_image_type":"default","og_image_url":null,"og_image_width":null,"og_image_height":null,"og_image_custom_url":null,"og_image_custom_fields":null,"og_video":"","og_custom_url":null,"og_article_section":null,"og_article_tags":null,"twitter_use_og":false,"twitter_card":"default","twitter_image_type":"default","twitter_image_url":null,"twitter_image_custom_url":null,"twitter_image_custom_fields":null,"twitter_title":null,"twitter_description":null,"schema":{"blockGraphs":[],"customGraphs":[],"default":{"data":{"Article":[],"Course":[],"Dataset":[],"FAQPage":[],"Movie":[],"Person":[],"Product":[],"ProductReview":[],"Car":[],"Recipe":[],"Service":[],"SoftwareApplication":[],"WebPage":[]},"graphName":"WebPage","isEnabled":true},"graphs":[]},"schema_type":"default","schema_type_options":null,"pillar_content":false,"robots_default":true,"robots_noindex":false,"robots_noarchive":false,"robots_nosnippet":false,"robots_nofollow":false,"robots_noimageindex":false,"robots_noodp":false,"robots_notranslate":false,"robots_max_snippet":"-1","robots_max_videopreview":"-1","robots_max_imagepreview":"large","priority":null,"frequency":"default","local_seo":null,"seo_analyzer_scan_date":"2026-07-15 10:00:39","breadcrumb_settings":null,"limit_modified_date":false,"open_ai":null,"ai":{"faqs":[],"keyPoints":[],"schemas":[],"titles":[],"descriptions":[],"socialPosts":{"email":{"subject":"","preview":"","content":""},"linkedin":[],"twitter":[],"facebook":[],"instagram":[]}},"created":"2026-07-15 09:56:32","updated":"2026-07-15 10:06:00"},"aioseo_breadcrumb":"<div class=\"aioseo-breadcrumbs\"><span class=\"aioseo-breadcrumb\">\n\t<a href=\"https:\/\/www.deutsche-yachten.de\/en\/\" title=\"Home\">Home<\/a>\n<\/span><span class=\"aioseo-breadcrumb-separator\">&raquo;<\/span><span class=\"aioseo-breadcrumb\">\n\t<a href=\"https:\/\/www.deutsche-yachten.de\/en\/news-mitglied\/uhsadel-rechtsanwalte-partgmbb\/\" title=\"Uhsadel Rechtsanw\u00e4lte PartGmbB\">Uhsadel Rechtsanw\u00e4lte PartGmbB<\/a>\n<\/span><span class=\"aioseo-breadcrumb-separator\">&raquo;<\/span><span class=\"aioseo-breadcrumb\">\n\tDeutsche Yachten welcomes two new members\n<\/span><\/div>","aioseo_breadcrumb_json":[{"label":"Home","link":"https:\/\/www.deutsche-yachten.de\/en\/"},{"label":"Uhsadel Rechtsanw\u00e4lte PartGmbB","link":"https:\/\/www.deutsche-yachten.de\/en\/news-mitglied\/uhsadel-rechtsanwalte-partgmbb\/"},{"label":"Deutsche Yachten welcomes two new members","link":"https:\/\/www.deutsche-yachten.de\/en\/news-beitrag\/deutsche-yachten-welcomes-two-new-members-2\/"}],"_links":{"self":[{"href":"https:\/\/www.deutsche-yachten.de\/en\/wp-json\/wp\/v2\/news-beitrag\/6018","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.deutsche-yachten.de\/en\/wp-json\/wp\/v2\/news-beitrag"}],"about":[{"href":"https:\/\/www.deutsche-yachten.de\/en\/wp-json\/wp\/v2\/types\/news-beitrag"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.deutsche-yachten.de\/en\/wp-json\/wp\/v2\/media\/6015"}],"wp:attachment":[{"href":"https:\/\/www.deutsche-yachten.de\/en\/wp-json\/wp\/v2\/media?parent=6018"}],"wp:term":[{"taxonomy":"news-mitglied","embeddable":true,"href":"https:\/\/www.deutsche-yachten.de\/en\/wp-json\/wp\/v2\/news-mitglied?post=6018"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}